{"id":465,"count":1,"description":"","link":"https:\/\/gameo.jp\/bang-dream\/tag\/%e5%ae%87%e7%94%b0%e5%b7%9d%e3%81%82%e3%81%93%e8%bf%bd%e3%81%84%e3%81%8b%e3%81%91%e3%81%a6%e3%81%84%e3%81%9f%e3%81%84","name":"\u5b87\u7530\u5ddd\u3042\u3053[\u8ffd\u3044\u304b\u3051\u3066\u3044\u305f\u3044]","slug":"%e5%ae%87%e7%94%b0%e5%b7%9d%e3%81%82%e3%81%93%e8%bf%bd%e3%81%84%e3%81%8b%e3%81%91%e3%81%a6%e3%81%84%e3%81%9f%e3%81%84","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gameo.jp\/bang-dream\/wp-json\/wp\/v2\/tags\/465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gameo.jp\/bang-dream\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gameo.jp\/bang-dream\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gameo.jp\/bang-dream\/wp-json\/wp\/v2\/posts?tags=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}