{"id":221,"count":1,"description":"","link":"https:\/\/gameo.jp\/pjsekai\/tag\/leo-need%e6%97%a5%e9%87%8e%e6%a3%ae%e5%bf%97%e6%ad%a9","name":"[Leo\/need]\u65e5\u91ce\u68ee\u5fd7\u6b69","slug":"leo-need%e6%97%a5%e9%87%8e%e6%a3%ae%e5%bf%97%e6%ad%a9","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/gameo.jp\/pjsekai\/wp-json\/wp\/v2\/tags\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gameo.jp\/pjsekai\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gameo.jp\/pjsekai\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gameo.jp\/pjsekai\/wp-json\/wp\/v2\/posts?tags=221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}